{"id":22,"date":"2025-02-13T18:59:43","date_gmt":"2025-02-13T18:59:43","guid":{"rendered":"https:\/\/intelproyect.com.gt\/?page_id=22"},"modified":"2025-03-10T02:24:16","modified_gmt":"2025-03-10T02:24:16","slug":"contactenos","status":"publish","type":"page","link":"https:\/\/intelproyect.com.gt\/index.php\/contactenos\/","title":{"rendered":"Cont\u00e1ctenos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Para inquietudes y comentarios por favor llene el siguiente formulario.<\/p>\n\n\n<div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-576b38ba-f76b-4485-a0bd-52fa1f36c141 wpforms-render-modern\" id=\"wpforms-53\"><form id=\"wpforms-form-53\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"53\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/22\" data-token=\"264da94a6781171bd3b22ff956cc7962\" data-token-time=\"1788335035\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-53-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Nombre <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-53-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" aria-errormessage=\"wpforms-53-field_1-error\" required><label for=\"wpforms-53-field_1\" class=\"wpforms-field-sublabel after\">Nombre<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-53-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" aria-errormessage=\"wpforms-53-field_1-last-error\" required><label for=\"wpforms-53-field_1-last\" class=\"wpforms-field-sublabel after\">Apellidos<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-53-field_17-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"17\"><label class=\"wpforms-field-label\" for=\"wpforms-53-field_17\">Empresa<\/label><input type=\"text\" id=\"wpforms-53-field_17\" class=\"wpforms-field-medium\" name=\"wpforms[fields][17]\" aria-errormessage=\"wpforms-53-field_17-error\" ><\/div><div id=\"wpforms-53-field_20-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"20\"><label class=\"wpforms-field-label\" for=\"wpforms-53-field_20\">Direcci\u00f3n<\/label><input type=\"text\" id=\"wpforms-53-field_20\" class=\"wpforms-field-medium\" name=\"wpforms[fields][20]\" aria-errormessage=\"wpforms-53-field_20-error\" ><\/div><div id=\"wpforms-53-field_18-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-53-field_18\">Tel\u00e9fono<\/label><input type=\"text\" id=\"wpforms-53-field_18\" class=\"wpforms-field-small\" name=\"wpforms[fields][18]\" aria-errormessage=\"wpforms-53-field_18-error\" ><\/div><div id=\"wpforms-53-field_19-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"19\"><label class=\"wpforms-field-label\" for=\"wpforms-53-field_19\">Pa\u00eds<\/label><input type=\"text\" id=\"wpforms-53-field_19\" class=\"wpforms-field-small\" name=\"wpforms[fields][19]\" aria-errormessage=\"wpforms-53-field_19-error\" ><\/div><div id=\"wpforms-53-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-53-field_2\">Correo electr\u00f3nico <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-53-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-53-field_2-error\" required><\/div><div id=\"wpforms-53-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-53-field_3\">Escriba su mensaje<\/label><textarea id=\"wpforms-53-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-53-field_3-error\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"53\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/intelproyect.com.gt\/index.php\/wp-json\/wp\/v2\/pages\/22\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-53\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/intelproyect.com.gt\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\"><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"<p>Para inquietudes y comentarios por favor llene el siguiente formulario.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-22","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/intelproyect.com.gt\/index.php\/wp-json\/wp\/v2\/pages\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intelproyect.com.gt\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/intelproyect.com.gt\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/intelproyect.com.gt\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intelproyect.com.gt\/index.php\/wp-json\/wp\/v2\/comments?post=22"}],"version-history":[{"count":10,"href":"https:\/\/intelproyect.com.gt\/index.php\/wp-json\/wp\/v2\/pages\/22\/revisions"}],"predecessor-version":[{"id":166,"href":"https:\/\/intelproyect.com.gt\/index.php\/wp-json\/wp\/v2\/pages\/22\/revisions\/166"}],"wp:attachment":[{"href":"https:\/\/intelproyect.com.gt\/index.php\/wp-json\/wp\/v2\/media?parent=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}